{"id":1623,"date":"2021-03-03T22:03:40","date_gmt":"2021-03-03T22:03:40","guid":{"rendered":"https:\/\/hakotech.pl\/en\/?page_id=1623"},"modified":"2021-06-01T09:03:13","modified_gmt":"2021-06-01T09:03:13","slug":"production-process","status":"publish","type":"page","link":"https:\/\/hakotech.pl\/en\/about-us\/production-process\/","title":{"rendered":"Production process"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; inner_shadow=&#8221;on&#8221; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; global_module=&#8221;36&#8243;][et_pb_fullwidth_post_title meta=&#8221;off&#8221; featured_image=&#8221;off&#8221; text_color=&#8221;light&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;|800|on||||||&#8221; title_line_height=&#8221;3em&#8221; background_color=&#8221;#BF3822&#8243; text_orientation=&#8221;center&#8221; custom_padding=&#8221;3px|||||&#8221;][\/et_pb_fullwidth_post_title][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.1&#8243; _module_preset=&#8221;default&#8221; min_height=&#8221;245px&#8221; custom_padding=&#8221;||0px|||&#8221;][et_pb_row _builder_version=&#8221;4.9.1&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.1&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<\/p>\n<h2>Production process<\/h2>\n<p>We produce elements based on documentation commended by a client. The production process is compatible with<strong> ISO standard<\/strong> and is controlled in every step by the <strong>ERP-SAP system<\/strong>.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.1&#8243; _module_preset=&#8221;default&#8221;][et_pb_row _builder_version=&#8221;4.9.1&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.1&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/hakotech.pl\/en\/wp-content\/uploads\/sites\/8\/2021\/04\/unnamed-file.png&#8221; title_text=&#8221;%93&#8243; align=&#8221;center&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#E8E8E8&#8243; custom_padding=&#8221;||7px|||&#8221; global_module=&#8221;2582&#8243; saved_tabs=&#8221;all&#8221;][et_pb_row _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_blurb title=&#8221;Products&#8221; content_max_width=&#8221;100%&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; header_level=&#8221;h2&#8243; header_font=&#8221;|800|on||||||&#8221; header_text_align=&#8221;center&#8221; text_orientation=&#8221;center&#8221;][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,2_3&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||8px|||&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/hakotech.pl\/en\/wp-content\/uploads\/sites\/8\/2021\/03\/Citymaster-1600.png&#8221; title_text=&#8221;Citymaster-1600&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||3px|||&#8221;]<\/p>\n<p style=\"text-align: justify;\">We create units for cleaning machines in internal and external parts of buildings, for maintaining cleanliness in communal areas and for maintaining green spaces. We take part proudly in a production of street sweepers, clamping rings, industrial vacuum cleaners, polishers which are used in all well-known chain stores in Poland and worldwide.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;\/en\/products\/&#8221; button_text=&#8221;Products&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221; global_module=&#8221;2583&#8243;][et_pb_row _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_blurb title=&#8221;Guarantee of quality&#8221; content_max_width=&#8221;100%&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; header_level=&#8221;h2&#8243; header_font=&#8221;|800|on||||||&#8221; header_text_align=&#8221;center&#8221; text_orientation=&#8221;center&#8221;]<\/p>\n<p>We work in in an accordance with ISO standards.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_6,1_6,1_6,1_6,1_6,1_6&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/hakotech.pl\/en\/wp-content\/uploads\/sites\/8\/2021\/03\/certyfikat_01.jpg&#8221; title_text=&#8221;certyfikat_01&#8243; show_in_lightbox=&#8221;on&#8221; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/hakotech.pl\/en\/wp-content\/uploads\/sites\/8\/2021\/03\/certyfikat_02.jpg&#8221; title_text=&#8221;certyfikat_02&#8243; show_in_lightbox=&#8221;on&#8221; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/hakotech.pl\/en\/wp-content\/uploads\/sites\/8\/2021\/03\/certyfikat_03.jpg&#8221; title_text=&#8221;certyfikat_03&#8243; show_in_lightbox=&#8221;on&#8221; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/hakotech.pl\/en\/wp-content\/uploads\/sites\/8\/2021\/03\/certyfikat_04.jpg&#8221; title_text=&#8221;certyfikat_04&#8243; show_in_lightbox=&#8221;on&#8221; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/hakotech.pl\/en\/wp-content\/uploads\/sites\/8\/2021\/03\/certyfikat_05.jpg&#8221; title_text=&#8221;certyfikat_05&#8243; show_in_lightbox=&#8221;on&#8221; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_image src=&#8221;https:\/\/hakotech.pl\/en\/wp-content\/uploads\/sites\/8\/2021\/03\/certyfikat_06.jpg&#8221; title_text=&#8221;certyfikat_06&#8243; show_in_lightbox=&#8221;on&#8221; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_button button_url=&#8221;\/en\/about-us\/quality-control\/&#8221; button_text=&#8221;Guarantee of quality&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#E8E8E8&#8243; global_module=&#8221;2576&#8243; saved_tabs=&#8221;all&#8221;][et_pb_row _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_blurb title=&#8221;Paint shop&#8221; content_max_width=&#8221;100%&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; header_level=&#8221;h2&#8243; header_font=&#8221;|800|on||||||&#8221; header_text_align=&#8221;center&#8221; text_orientation=&#8221;center&#8221;]<\/p>\n<p>Our paint shop was established in 2018 and is one of the most modern paint shops in Poland.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;2_3,1_3&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_video src=&#8221;https:\/\/youtu.be\/lht3GqVhSmE&#8221; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_video][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<\/p>\n<p style=\"text-align: justify;\">The technical requirements for cycle times and dimensions for large and small parts are very different, therefore our paint shop consists of two separated painting lines with a common usage of pre-treatment, chemical tunnel, cooling section and hardening oven. Powder paint shop rooms, masking and demasking machines are separated because of the differences in components. (Weights; suspension variants).<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][et_pb_button button_url=&#8221;\/en\/paint-shop\/&#8221; button_text=&#8221;Paint shop&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; global_module=&#8221;2590&#8243;][et_pb_row _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_blurb title=&#8221;Machinery Park&#8221; content_max_width=&#8221;100%&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; header_level=&#8221;h2&#8243; header_font=&#8221;|800|on||||||&#8221; header_text_align=&#8221;center&#8221; text_orientation=&#8221;center&#8221;]<\/p>\n<p>We have the newest machinery park<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;3_5,2_5&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_gallery gallery_ids=&#8221;1414,1420,1419,1418,1416,1417,1413,1412,1405,1404,1402,1401,1398,1397,1396,1395&#8243; gallery_orderby=&#8221;rand&#8221; posts_number=&#8221;2&#8243; show_title_and_caption=&#8221;off&#8221; show_pagination=&#8221;off&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_gallery][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<\/p>\n<p style=\"text-align: justify;\">We have the newest machinery park which includes saw, guillotine, rolling mill, 60T\/300T\/500T press, manual lathe, numerical lathe, die cutter, sandblaster, flanging press, eccentric press, bending brake, drills, pressure welding machines, tools for stud welding, MIG\/MAG welders, tig-welding machines, welders and covered electrode, lasers.<br \/>We get the max quality of offered products which the quality control department watches over.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_button button_url=&#8221;\/en\/machinery\/&#8221; button_text=&#8221;Machines- specification&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f9f9f9&#8243; custom_padding=&#8221;50px|||||&#8221; top_divider_arrangement=&#8221;above_content&#8221; border_width_top=&#8221;4px&#8221; border_color_top=&#8221;#BF3822&#8243; global_module=&#8221;2548&#8243;][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;]<\/p>\n<div class=\"w-iconbox iconpos_left style_default color_primary align_center no_title\">\n<div class=\"w-iconbox-meta\">\n<div class=\"w-iconbox-text\">\n<div class=\"w-iconbox iconpos_left style_default color_primary align_center no_title\">\n<div class=\"w-iconbox-meta\">\n<div class=\"w-iconbox-text\">\n<p><span>Hako Technology Sp. z o.o.<br \/>Since 1997, together<br \/>NIP: 7821976958, <br \/>REGON: 631031259<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<\/p>\n<div class=\"w-iconbox iconpos_left style_default color_primary align_center no_title\">\n<div class=\"w-iconbox-meta\">\n<div class=\"w-iconbox-text\">\n<div class=\"w-iconbox iconpos_left style_default color_primary align_center no_title\">\n<div class=\"w-iconbox-meta\">\n<div class=\"w-iconbox-text\">\n<p>+48<span>\u00a0<\/span><strong>94 347 04 04<\/strong><br \/>+48<span>\u00a0<\/span><strong>94 316 19 43<\/strong><br \/><a href=\"mailto:sekretariat@hakotech.pl\">sekretariat@hakotech.pl<\/a><\/p>\n<p>Secretary: +48<span>\u00a0<\/span><strong>605 409 033<\/strong><br \/>Sale: +48<span>\u00a0<\/span><strong>502 699 735<\/strong><br \/>Shopping: +48<span>\u00a0<\/span><strong>603 902 875<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.9.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_text _builder_version=&#8221;4.9.4&#8243; _module_preset=&#8221;default&#8221;]<\/p>\n<div class=\"w-iconbox iconpos_left style_default color_primary align_center no_title\">\n<div class=\"w-iconbox-meta\">\n<div class=\"w-iconbox-text\">\n<p><span class=\"fsx04\">Cha<\/span><span class=\"fsx04\">\u0142upy 30<br \/>76-024 \u015awieszyno<br \/><\/span><span class=\"fsx04\">Poland<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Production process We produce elements based on documentation commended by a client. The production process is compatible with ISO standard and is controlled in every step by the ERP-SAP system.We create units for cleaning machines in internal and external parts of buildings, for maintaining cleanliness in communal areas and for maintaining green spaces. We take [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1594,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-1623","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Production process - EN Hako Technology Sp. z o.o.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hakotech.pl\/en\/about-us\/production-process\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Production process - EN Hako Technology Sp. z o.o.\" \/>\n<meta property=\"og:description\" content=\"Production process We produce elements based on documentation commended by a client. The production process is compatible with ISO standard and is controlled in every step by the ERP-SAP system.We create units for cleaning machines in internal and external parts of buildings, for maintaining cleanliness in communal areas and for maintaining green spaces. We take [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hakotech.pl\/en\/about-us\/production-process\/\" \/>\n<meta property=\"og:site_name\" content=\"EN Hako Technology Sp. z o.o.\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-01T09:03:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hakotech.pl\\\/en\\\/about-us\\\/production-process\\\/\",\"url\":\"https:\\\/\\\/hakotech.pl\\\/en\\\/about-us\\\/production-process\\\/\",\"name\":\"Production process - EN Hako Technology Sp. z o.o.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hakotech.pl\\\/en\\\/#website\"},\"datePublished\":\"2021-03-03T22:03:40+00:00\",\"dateModified\":\"2021-06-01T09:03:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hakotech.pl\\\/en\\\/about-us\\\/production-process\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hakotech.pl\\\/en\\\/about-us\\\/production-process\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hakotech.pl\\\/en\\\/about-us\\\/production-process\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/hakotech.pl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About us\",\"item\":\"https:\\\/\\\/hakotech.pl\\\/en\\\/about-us\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Production process\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hakotech.pl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/hakotech.pl\\\/en\\\/\",\"name\":\"EN Hako Technology Sp. z o.o.\",\"description\":\"Hako Technology\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hakotech.pl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Production process - EN Hako Technology Sp. z o.o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hakotech.pl\/en\/about-us\/production-process\/","og_locale":"pl_PL","og_type":"article","og_title":"Production process - EN Hako Technology Sp. z o.o.","og_description":"Production process We produce elements based on documentation commended by a client. The production process is compatible with ISO standard and is controlled in every step by the ERP-SAP system.We create units for cleaning machines in internal and external parts of buildings, for maintaining cleanliness in communal areas and for maintaining green spaces. We take [&hellip;]","og_url":"https:\/\/hakotech.pl\/en\/about-us\/production-process\/","og_site_name":"EN Hako Technology Sp. z o.o.","article_modified_time":"2021-06-01T09:03:13+00:00","twitter_card":"summary_large_image","twitter_misc":{"Szacowany czas czytania":"7 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hakotech.pl\/en\/about-us\/production-process\/","url":"https:\/\/hakotech.pl\/en\/about-us\/production-process\/","name":"Production process - EN Hako Technology Sp. z o.o.","isPartOf":{"@id":"https:\/\/hakotech.pl\/en\/#website"},"datePublished":"2021-03-03T22:03:40+00:00","dateModified":"2021-06-01T09:03:13+00:00","breadcrumb":{"@id":"https:\/\/hakotech.pl\/en\/about-us\/production-process\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hakotech.pl\/en\/about-us\/production-process\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hakotech.pl\/en\/about-us\/production-process\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/hakotech.pl\/en\/"},{"@type":"ListItem","position":2,"name":"About us","item":"https:\/\/hakotech.pl\/en\/about-us\/"},{"@type":"ListItem","position":3,"name":"Production process"}]},{"@type":"WebSite","@id":"https:\/\/hakotech.pl\/en\/#website","url":"https:\/\/hakotech.pl\/en\/","name":"EN Hako Technology Sp. z o.o.","description":"Hako Technology","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hakotech.pl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"}]}},"_links":{"self":[{"href":"https:\/\/hakotech.pl\/en\/wp-json\/wp\/v2\/pages\/1623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hakotech.pl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hakotech.pl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hakotech.pl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hakotech.pl\/en\/wp-json\/wp\/v2\/comments?post=1623"}],"version-history":[{"count":13,"href":"https:\/\/hakotech.pl\/en\/wp-json\/wp\/v2\/pages\/1623\/revisions"}],"predecessor-version":[{"id":2836,"href":"https:\/\/hakotech.pl\/en\/wp-json\/wp\/v2\/pages\/1623\/revisions\/2836"}],"up":[{"embeddable":true,"href":"https:\/\/hakotech.pl\/en\/wp-json\/wp\/v2\/pages\/1594"}],"wp:attachment":[{"href":"https:\/\/hakotech.pl\/en\/wp-json\/wp\/v2\/media?parent=1623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}